{"id":119,"count":5,"description":"","link":"https:\/\/www.bowditch.com\/craftbrewerylegalblog\/tag\/farmer-breweries\/","name":"farmer-breweries","slug":"farmer-breweries","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>farmer-breweries Archives - At the Bar With Bowditch<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bowditch.com\/craftbrewerylegalblog\/tag\/farmer-breweries\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"farmer-breweries Archives - At the Bar With Bowditch\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bowditch.com\/craftbrewerylegalblog\/tag\/farmer-breweries\/\" \/>\n<meta property=\"og:site_name\" content=\"At the Bar With Bowditch\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.bowditch.com\\\/craftbrewerylegalblog\\\/tag\\\/farmer-breweries\\\/\",\"url\":\"https:\\\/\\\/www.bowditch.com\\\/craftbrewerylegalblog\\\/tag\\\/farmer-breweries\\\/\",\"name\":\"farmer-breweries Archives - At the Bar With Bowditch\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bowditch.com\\\/craftbrewerylegalblog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bowditch.com\\\/craftbrewerylegalblog\\\/tag\\\/farmer-breweries\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bowditch.com\\\/craftbrewerylegalblog\\\/tag\\\/farmer-breweries\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.bowditch.com\\\/craftbrewerylegalblog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"farmer-breweries\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bowditch.com\\\/craftbrewerylegalblog\\\/#website\",\"url\":\"https:\\\/\\\/www.bowditch.com\\\/craftbrewerylegalblog\\\/\",\"name\":\"At the Bar With Bowditch\",\"description\":\"A Legal Blog for the Craft Brewing Community\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bowditch.com\\\/craftbrewerylegalblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"farmer-breweries Archives - At the Bar With Bowditch","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bowditch.com\/craftbrewerylegalblog\/tag\/farmer-breweries\/","og_locale":"en_US","og_type":"article","og_title":"farmer-breweries Archives - At the Bar With Bowditch","og_url":"https:\/\/www.bowditch.com\/craftbrewerylegalblog\/tag\/farmer-breweries\/","og_site_name":"At the Bar With Bowditch","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.bowditch.com\/craftbrewerylegalblog\/tag\/farmer-breweries\/","url":"https:\/\/www.bowditch.com\/craftbrewerylegalblog\/tag\/farmer-breweries\/","name":"farmer-breweries Archives - At the Bar With Bowditch","isPartOf":{"@id":"https:\/\/www.bowditch.com\/craftbrewerylegalblog\/#website"},"breadcrumb":{"@id":"https:\/\/www.bowditch.com\/craftbrewerylegalblog\/tag\/farmer-breweries\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.bowditch.com\/craftbrewerylegalblog\/tag\/farmer-breweries\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bowditch.com\/craftbrewerylegalblog\/"},{"@type":"ListItem","position":2,"name":"farmer-breweries"}]},{"@type":"WebSite","@id":"https:\/\/www.bowditch.com\/craftbrewerylegalblog\/#website","url":"https:\/\/www.bowditch.com\/craftbrewerylegalblog\/","name":"At the Bar With Bowditch","description":"A Legal Blog for the Craft Brewing Community","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bowditch.com\/craftbrewerylegalblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.bowditch.com\/craftbrewerylegalblog\/wp-json\/wp\/v2\/tags\/119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bowditch.com\/craftbrewerylegalblog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.bowditch.com\/craftbrewerylegalblog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.bowditch.com\/craftbrewerylegalblog\/wp-json\/wp\/v2\/posts?tags=119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}